{"id":290,"date":"2023-11-29T19:07:44","date_gmt":"2023-11-29T18:07:44","guid":{"rendered":"https:\/\/tiefbau-oldenburg.de\/?page_id=290"},"modified":"2026-02-07T16:52:40","modified_gmt":"2026-02-07T15:52:40","slug":"datenschutzerklaerung","status":"publish","type":"page","link":"https:\/\/tiefbau-oldenburg.de\/index.php\/datenschutzerklaerung\/","title":{"rendered":"Datenschutzerkl\u00e4rung"},"content":{"rendered":"<section class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_empty_space height=&#8220;50px&#8220;][vc_row_inner][vc_column_inner offset=&#8220;vc_col-sm-offset-0 vc_col-xs-offset-1 vc_col-xs-4\/5&#8243;][vc_custom_heading text=&#8220;Datenschutzerkl\u00e4rung&#8220; use_theme_fonts=&#8220;yes&#8220;][vc_column_text]<strong>Allgemeine Hinweise<\/strong><\/p>\n<p>Die folgenden Hinweise geben einen einfachen \u00dcberblick dar\u00fcber, was mit Ihren personenbezogenen Daten passiert, wenn Sie unsere Webseite besuchen. Personenbezogene Daten sind alle Daten, mit denen Sie pers\u00f6nlich identifiziert werden k\u00f6nnen. Ausf\u00fchrliche Informationen zum Thema Datenschutz entnehmen Sie unserer unter diesem Text aufgef\u00fchrten Datenschutzerkl\u00e4rung.<\/p>\n<p><strong>Datenerfassung auf unserer Webseite<\/strong><\/p>\n<p>Wer ist verantwortlich f\u00fcr die Datenerfassung auf dieser Webseite?<\/p>\n<p>Die Datenverarbeitung auf dieser Website erfolgt durch den Websitebetreiber. Dessen Kontaktdaten k\u00f6nnen Sie dem Impressum dieser Website entnehmen.<\/p>\n<p><strong>Wie erfassen wir Ihre Daten?<\/strong><\/p>\n<p>Ihre Daten werden zum einen dadurch erhoben, dass Sie uns diese mitteilen. Hierbei kann es sich z.B. um Daten handeln, die Sie in ein Kontaktformular eingeben.<\/p>\n<p>Andere Daten werden automatisch beim Besuch der Website durch unsere IT-Systeme erfasst. Das sind vor allem technische Daten (z.B. Internetbrowser, Betriebssystem oder Uhrzeit des Seitenaufrufs). Die Erfassung dieser Daten erfolgt automatisch, sobald Sie unsere Website betreten.<\/p>\n<p><strong>Wof\u00fcr nutzen wir Ihre Daten?<\/strong><\/p>\n<p>Ein Teil der Daten wird erhoben, um eine fehlerfreie Bereitstellung der Website zu gew\u00e4hrleisten. Andere Daten k\u00f6nnen zur Analyse Ihres Nutzerverhaltens verwendet werden.<\/p>\n<p><strong>Welche Rechte haben Sie bez\u00fcglich Ihrer Daten?<\/strong><\/p>\n<p>Sie haben jederzeit das Recht unentgeltlich Auskunft \u00fcber Herkunft, Empf\u00e4nger und Zweck Ihrer gespeicherten personenbezogenen Daten zu erhalten. Sie haben au\u00dferdem ein Recht, die Berichtigung, Sperrung oder L\u00f6schung dieser Daten zu verlangen. Hierzu sowie zu weiteren Fragen zum Thema Datenschutz k\u00f6nnen Sie sich jederzeit unter der im Impressum angegebenen Adresse an uns wenden. Des Weiteren steht Ihnen ein Beschwerderecht bei der zust\u00e4ndigen Aufsichtsbeh\u00f6rde zu.<\/p>\n<p><strong>Analyse-Tools und <\/strong><strong><span lang=\"en-US\">Tools<\/span><\/strong><strong> von Drittanbietern<\/strong><\/p>\n<p>Beim Besuch unserer Website kann Ihr Surf-Verhalten statistisch ausgewertet werden. Das geschieht vor allem mit Cookies und mit sogenannten Analyseprogrammen. Die Analyse Ihres Surf-Verhaltens erfolgt in der Regel anonym; das Surf-Verhalten kann nicht zu Ihnen zur\u00fcckverfolgt werden. Sie k\u00f6nnen dieser Analyse widersprechen oder sie durch die Nichtbenutzung bestimmter <span lang=\"en-US\">Tools<\/span> verhindern. Details hierzu entnehmen Sie unserer Datenschutzerkl\u00e4rung unter der \u00dcberschrift \u201cDrittmodule und Analysetools\u201d.<\/p>\n<p>Sie k\u00f6nnen dieser Analyse widersprechen. \u00dcber die Widerspruchsm\u00f6glichkeiten werden wir Sie in dieser Datenschutzerkl\u00e4rung informieren.<\/p>\n<h2 class=\"western\"><\/h2>\n<h3 class=\"western\">Allgemeine Hinweise und Pflichtinformationen<\/h3>\n<p><strong>Datenschutz<\/strong><\/p>\n<p>Die Betreiber dieser Seiten nehmen den Schutz Ihrer pers\u00f6nlichen Daten sehr ernst. Wir behandeln Ihre personenbezogenen Daten vertraulich und entsprechend der gesetzlichen Datenschutzvorschriften sowie dieser Datenschutzerkl\u00e4rung.<\/p>\n<p>Wenn Sie diese Webseite benutzen, werden verschiedene personenbezogene Daten erhoben. Personenbezogene Daten sind Daten, mit denen Sie pers\u00f6nlich identifiziert werden k\u00f6nnen. Die vorliegende Datenschutzerkl\u00e4rung erl\u00e4utert, welche Daten wir erheben und wof\u00fcr wir sie nutzen. Sie erl\u00e4utert auch, wie und zu welchem Zweck das geschieht.<\/p>\n<p>Wir weisen darauf hin, dass die Daten\u00fcbertragung im Internet (z.B. bei der Kommunikation per E-Mail) Sicherheitsl\u00fccken aufweisen kann. Ein l\u00fcckenloser Schutz der Daten vor dem Zugriff durch Dritte ist nicht m\u00f6glich.<\/p>\n<p><strong>Hinweis zur verantwortlichen Stelle<\/strong><\/p>\n<p>Die verantwortliche Stelle f\u00fcr die Datenverarbeitung auf dieser Website ist:<\/p>\n<p>Kowalski Tiefbau GmbH &amp; Co. KG<br \/>\nAm Schlatt 28a<br \/>\nD-26203 Wardenburg<br \/>\nTel.: 04407\/8125<br \/>\nFax: 04407\/979682<\/p>\n<p><a href=\"mailto:info@tiefbau-oldenburg.de\">info@tiefbau-oldenburg.de<\/a><\/p>\n<p>Verantwortliche Stelle ist die nat\u00fcrliche oder juristische Person, die allein oder gemeinsam mit anderen \u00fcber die Zwecke und Mittel der Verarbeitung von personenbezogenen Daten (z.B. Namen, E-Mail-Adressen o. \u00c4.) entscheidet.<\/p>\n<p><strong>Widerruf Ihrer Einwilligung zur Datenverarbeitung<\/strong><\/p>\n<p>Viele Datenverarbeitungsvorg\u00e4nge sind nur mit Ihrer ausdr\u00fccklichen Einwilligung m\u00f6glich. Sie k\u00f6nnen eine bereits erteilte Einwilligung jederzeit widerrufen. Dazu reicht eine formlose Mitteilung per E-Mail an uns. Die Rechtm\u00e4\u00dfigkeit der bis zum Widerruf erfolgten Datenverarbeitung bleibt vom Widerruf unber\u00fchrt.<\/p>\n<p><strong>Recht auf Daten\u00fcbertragbarkeit<\/strong><\/p>\n<p>Sie haben das Recht, Daten, die wir auf Grundlage Ihrer Einwilligung oder in Erf\u00fcllung eines Vertrags automatisiert verarbeiten, an sich oder an einen Dritten in einem g\u00e4ngigen, maschinenlesbaren Format aush\u00e4ndigen zu lassen. Sofern Sie die direkte \u00dcbertragung der Daten an einen anderen Verantwortlichen verlangen, erfolgt dies nur, soweit es technisch machbar ist.<\/p>\n<p><strong>SSL- bzw. TLS-Verschl\u00fcsselung<\/strong><\/p>\n<p>Diese Seite nutzt aus Sicherheitsgr\u00fcnden und zum Schutz der \u00dcbertragung vertraulicher Inhalte, wie zum Beispiel Bestellungen oder Anfragen, die Sie an uns als Seitenbetreiber senden, eine SSL-bzw. TLS-Verschl\u00fcsselung. Eine verschl\u00fcsselte Verbindung erkennen Sie daran, dass die Adresszeile des Browsers von \u201chttp:\/\/\u201d auf \u201chttps:\/\/\u201d wechselt und an dem Schloss-Symbol in Ihrer Browserzeile. Wenn die SSL- bzw. TLS-Verschl\u00fcsselung aktiviert ist, k\u00f6nnen die Daten, die Sie an uns \u00fcbermitteln, nicht von Dritten mitgelesen werden.<\/p>\n<p><strong>Auskunft, Sperrung, L\u00f6schung<\/strong><\/p>\n<p>Sie haben im Rahmen der geltenden gesetzlichen Bestimmungen jederzeit das Recht auf unentgeltliche Auskunft \u00fcber Ihre gespeicherten personenbezogenen Daten, deren Herkunft und Empf\u00e4nger und den Zweck der Datenverarbeitung und ggf. ein Recht auf Berichtigung, Sperrung oder L\u00f6schung dieser Daten. Hierzu sowie zu weiteren Fragen zum Thema personenbezogene Daten k\u00f6nnen Sie sich jederzeit unter der im Impressum angegebenen Adresse an uns wenden.<\/p>\n<p><strong>Widerspruch gegen Werbe-Mails<\/strong><\/p>\n<p>Der Nutzung von im Rahmen der Impressumspflicht ver\u00f6ffentlichten Kontaktdaten zur \u00dcbersendung von nicht ausdr\u00fccklich angeforderter Werbung und Informationsmaterialien wird hiermit widersprochen. Die Betreiber der Seiten behalten sich ausdr\u00fccklich rechtliche Schritte im Falle der unverlangten Zusendung von Werbeinformationen, etwa durch Spam-E-Mails, vor.<\/p>\n<h2 class=\"western\"><\/h2>\n<h3 class=\"western\">Datenerfassung auf unserer Website<\/h3>\n<p><strong>Cookies<\/strong><\/p>\n<p>Die Internetseiten verwenden teilweise so genannte Cookies. Cookies richten auf Ihrem Rechner keinen Schaden an und enthalten keine Viren. Cookies dienen dazu, unser Angebot nutzerfreundlicher, effektiver und sicherer zu machen. Cookies sind kleine Textdateien, die auf Ihrem Rechner abgelegt werden und die Ihr Browser speichert. Die meisten der von uns verwendeten Cookies sind so genannte \u201cSession-Cookies\u201d. Sie werden nach Ende Ihres Besuchs automatisch gel\u00f6scht. Andere Cookies bleiben auf Ihrem Endger\u00e4t gespeichert bis Sie diese l\u00f6schen. Diese Cookies erm\u00f6glichen es uns, Ihren Browser beim n\u00e4chsten Besuch wiederzuerkennen. Sie k\u00f6nnen Ihren Browser so einstellen, dass Sie \u00fcber das Setzen von Cookies informiert werden und Cookies nur im Einzelfall erlauben, die Annahme von Cookies f\u00fcr bestimmte F\u00e4lle oder generell ausschlie\u00dfen sowie das automatische L\u00f6schen der Cookies beim Schlie\u00dfen des Browser aktivieren. Bei der Deaktivierung von Cookies kann die Funktionalit\u00e4t dieser Website eingeschr\u00e4nkt sein.<\/p>\n<p>Cookies, die zur Durchf\u00fchrung des elektronischen Kommunikationsvorgangs oder zur Bereitstellung bestimmter, von Ihnen erw\u00fcnschter Funktionen (z.B. Warenkorbfunktion) erforderlich sind, werden auf Grundlage von Art. 6 Abs. 1 lit. f DSGVO gespeichert. Der Webseitenbetreiber hat ein berechtigtes Interesse an der Speicherung von Cookies zur technisch fehlerfreien und optimierten Bereitstellung seiner Dienste. Soweit andere Cookies (z.B. Cookies zur Analyse Ihres Surfverhaltens) gespeichert werden, werden diese in dieser Datenschutzerkl\u00e4rung gesondert behandelt.<\/p>\n<p><strong>Server-Log-Dateien<\/strong><\/p>\n<p>Der <span lang=\"en-US\">Provider<\/span> der Seiten erhebt und speichert automatisch Informationen in so genannten Server-Log-Dateien, die Ihr Browser automatisch an uns \u00fcbermittelt. Dies sind:<\/p>\n<ul>\n<li>Browsertyp und Browserversion<\/li>\n<li>verwendetes Betriebssystem<\/li>\n<li>Referrer URL<\/li>\n<li>Hostname des zugreifenden Rechners<\/li>\n<li>Uhrzeit der Serveranfrage<\/li>\n<li>IP-Adresse<\/li>\n<\/ul>\n<p>Eine Zusammenf\u00fchrung dieser Daten mit anderen Datenquellen wird nicht vorgenommen.<\/p>\n<p>Grundlage f\u00fcr die Datenverarbeitung ist Art. 6 Abs. 1 lit. b DSGVO, der die Verarbeitung von Daten zur Erf\u00fcllung eines Vertrags oder vorvertraglicher Ma\u00dfnahmen gestattet.<\/p>\n<p><strong>Kontaktformular<\/strong><\/p>\n<p>Wenn Sie uns per Kontaktformular Anfragen zukommen lassen, werden Ihre Angaben aus dem Anfrageformular inklusive der von Ihnen dort angegebenen Kontaktdaten zwecks Bearbeitung der Anfrage und f\u00fcr den Fall von Anschlussfragen bei uns gespeichert. Diese Daten geben wir nicht ohne Ihre Einwilligung weiter.<\/p>\n<p>Die Verarbeitung der in das Kontaktformular eingegebenen Daten erfolgt somit ausschlie\u00dflich auf Grundlage Ihrer Einwilligung (Art. 6 Abs. 1 lit. a DSGVO). Sie k\u00f6nnen diese Einwilligung jederzeit widerrufen. Dazu reicht eine formlose Mitteilung per E-Mail an uns. Die Rechtm\u00e4\u00dfigkeit der bis zum Widerruf erfolgten Datenverarbeitungsvorg\u00e4nge bleibt vom Widerruf unber\u00fchrt.<\/p>\n<p>Die von Ihnen im Kontaktformular eingegebenen Daten verbleiben bei uns, bis Sie uns zur L\u00f6schung auffordern, Ihre Einwilligung zur Speicherung widerrufen oder der Zweck f\u00fcr die Datenspeicherung entf\u00e4llt (z.B. nach abgeschlossener Bearbeitung Ihrer Anfrage). Zwingende gesetzliche Bestimmungen \u2013 insbesondere Aufbewahrungsfristen \u2013 bleiben unber\u00fchrt.<\/p>\n<h3 class=\"western\">Plugins und <span lang=\"en-US\">Tools<\/span><\/h3>\n<p><strong>Google Web Fonts<\/strong><\/p>\n<p>Diese Seite nutzt zur einheitlichen Darstellung von Schriftarten so genannte Web Fonts, die von Google bereitgestellt werden. Beim Aufruf einer Seite l\u00e4dt Ihr Browser die ben\u00f6tigten Web Fonts in ihren Browser-Cache, um Texte und Schriftarten korrekt anzuzeigen.<\/p>\n<p>Zu diesem Zweck muss der von Ihnen verwendete Browser Verbindung zu den Servern von Google aufnehmen. Hierdurch erlangt Google Kenntnis dar\u00fcber, dass \u00fcber Ihre IP-Adresse unsere Website aufgerufen wurde. Die Nutzung von Google Web Fonts erfolgt im Interesse einer einheitlichen und ansprechenden Darstellung unserer Online-Angebote. Dies stellt ein berechtigtes Interesse im Sinne von Art. 6 Abs. 1 lit. f DSGVO dar.<\/p>\n<p>Wenn Ihr Browser Web Fonts nicht unterst\u00fctzt, wird eine Standardschrift von Ihrem <span lang=\"en-US\">Computer<\/span> genutzt.<\/p>\n<p>Weitere Informationen zu Google Web Fonts finden Sie unter <a href=\"https:\/\/developers.google.com\/fonts\/faq\" target=\"_blank\" rel=\"noopener\">https:\/\/developers.google.com\/fonts\/faq<\/a> und in der Datenschutzerkl\u00e4rung von Google: <a href=\"https:\/\/www.google.com\/policies\/privacy\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.google.com\/policies\/privacy\/<\/a>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]<\/p>\n<\/section>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_empty_space height=&#8220;50px&#8220;][vc_row_inner][vc_column_inner offset=&#8220;vc_col-sm-offset-0 vc_col-xs-offset-1 vc_col-xs-4\/5&#8243;][vc_custom_heading text=&#8220;Datenschutzerkl\u00e4rung&#8220; use_theme_fonts=&#8220;yes&#8220;][vc_column_text]Allgemeine Hinweise Die folgenden Hinweise geben einen einfachen \u00dcberblick dar\u00fcber, was mit Ihren personenbezogenen Daten passiert, wenn Sie unsere Webseite besuchen. Personenbezogene Daten sind alle Daten, mit denen Sie pers\u00f6nlich identifiziert werden k\u00f6nnen. Ausf\u00fchrliche Informationen zum Thema Datenschutz entnehmen Sie unserer unter diesem Text aufgef\u00fchrten Datenschutzerkl\u00e4rung. Datenerfassung auf unserer Webseite Wer ist verantwortlich f\u00fcr die Datenerfassung auf dieser Webseite? Die Datenverarbeitung auf dieser Website [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-290","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Datenschutzerkl\u00e4rung - Kowalski Tiefbau<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tiefbau-oldenburg.de\/index.php\/datenschutzerklaerung\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Datenschutzerkl\u00e4rung - Kowalski Tiefbau\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column][vc_empty_space height=&#8220;50px&#8220;][vc_row_inner][vc_column_inner offset=&#8220;vc_col-sm-offset-0 vc_col-xs-offset-1 vc_col-xs-4\/5&#8243;][vc_custom_heading text=&#8220;Datenschutzerkl\u00e4rung&#8220; use_theme_fonts=&#8220;yes&#8220;][vc_column_text]Allgemeine Hinweise Die folgenden Hinweise geben einen einfachen \u00dcberblick dar\u00fcber, was mit Ihren personenbezogenen Daten passiert, wenn Sie unsere Webseite besuchen. Personenbezogene Daten sind alle Daten, mit denen Sie pers\u00f6nlich identifiziert werden k\u00f6nnen. Ausf\u00fchrliche Informationen zum Thema Datenschutz entnehmen Sie unserer unter diesem Text aufgef\u00fchrten Datenschutzerkl\u00e4rung. Datenerfassung auf unserer Webseite Wer ist verantwortlich f\u00fcr die Datenerfassung auf dieser Webseite? Die Datenverarbeitung auf dieser Website [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tiefbau-oldenburg.de\/index.php\/datenschutzerklaerung\/\" \/>\n<meta property=\"og:site_name\" content=\"Kowalski Tiefbau\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-07T15:52:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"8\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/tiefbau-oldenburg.de\/index.php\/datenschutzerklaerung\/\",\"url\":\"https:\/\/tiefbau-oldenburg.de\/index.php\/datenschutzerklaerung\/\",\"name\":\"Datenschutzerkl\u00e4rung - Kowalski Tiefbau\",\"isPartOf\":{\"@id\":\"https:\/\/tiefbau-oldenburg.de\/#website\"},\"datePublished\":\"2023-11-29T18:07:44+00:00\",\"dateModified\":\"2026-02-07T15:52:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/tiefbau-oldenburg.de\/index.php\/datenschutzerklaerung\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/tiefbau-oldenburg.de\/index.php\/datenschutzerklaerung\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/tiefbau-oldenburg.de\/index.php\/datenschutzerklaerung\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/tiefbau-oldenburg.de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Datenschutzerkl\u00e4rung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/tiefbau-oldenburg.de\/#website\",\"url\":\"https:\/\/tiefbau-oldenburg.de\/\",\"name\":\"Kowalski Tiefbau\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/tiefbau-oldenburg.de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Datenschutzerkl\u00e4rung - Kowalski Tiefbau","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tiefbau-oldenburg.de\/index.php\/datenschutzerklaerung\/","og_locale":"de_DE","og_type":"article","og_title":"Datenschutzerkl\u00e4rung - Kowalski Tiefbau","og_description":"[vc_row][vc_column][vc_empty_space height=&#8220;50px&#8220;][vc_row_inner][vc_column_inner offset=&#8220;vc_col-sm-offset-0 vc_col-xs-offset-1 vc_col-xs-4\/5&#8243;][vc_custom_heading text=&#8220;Datenschutzerkl\u00e4rung&#8220; use_theme_fonts=&#8220;yes&#8220;][vc_column_text]Allgemeine Hinweise Die folgenden Hinweise geben einen einfachen \u00dcberblick dar\u00fcber, was mit Ihren personenbezogenen Daten passiert, wenn Sie unsere Webseite besuchen. Personenbezogene Daten sind alle Daten, mit denen Sie pers\u00f6nlich identifiziert werden k\u00f6nnen. Ausf\u00fchrliche Informationen zum Thema Datenschutz entnehmen Sie unserer unter diesem Text aufgef\u00fchrten Datenschutzerkl\u00e4rung. Datenerfassung auf unserer Webseite Wer ist verantwortlich f\u00fcr die Datenerfassung auf dieser Webseite? Die Datenverarbeitung auf dieser Website [&hellip;]","og_url":"https:\/\/tiefbau-oldenburg.de\/index.php\/datenschutzerklaerung\/","og_site_name":"Kowalski Tiefbau","article_modified_time":"2026-02-07T15:52:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"8\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/tiefbau-oldenburg.de\/index.php\/datenschutzerklaerung\/","url":"https:\/\/tiefbau-oldenburg.de\/index.php\/datenschutzerklaerung\/","name":"Datenschutzerkl\u00e4rung - Kowalski Tiefbau","isPartOf":{"@id":"https:\/\/tiefbau-oldenburg.de\/#website"},"datePublished":"2023-11-29T18:07:44+00:00","dateModified":"2026-02-07T15:52:40+00:00","breadcrumb":{"@id":"https:\/\/tiefbau-oldenburg.de\/index.php\/datenschutzerklaerung\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tiefbau-oldenburg.de\/index.php\/datenschutzerklaerung\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/tiefbau-oldenburg.de\/index.php\/datenschutzerklaerung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/tiefbau-oldenburg.de\/"},{"@type":"ListItem","position":2,"name":"Datenschutzerkl\u00e4rung"}]},{"@type":"WebSite","@id":"https:\/\/tiefbau-oldenburg.de\/#website","url":"https:\/\/tiefbau-oldenburg.de\/","name":"Kowalski Tiefbau","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tiefbau-oldenburg.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/tiefbau-oldenburg.de\/index.php\/wp-json\/wp\/v2\/pages\/290","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tiefbau-oldenburg.de\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/tiefbau-oldenburg.de\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/tiefbau-oldenburg.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tiefbau-oldenburg.de\/index.php\/wp-json\/wp\/v2\/comments?post=290"}],"version-history":[{"count":5,"href":"https:\/\/tiefbau-oldenburg.de\/index.php\/wp-json\/wp\/v2\/pages\/290\/revisions"}],"predecessor-version":[{"id":330,"href":"https:\/\/tiefbau-oldenburg.de\/index.php\/wp-json\/wp\/v2\/pages\/290\/revisions\/330"}],"wp:attachment":[{"href":"https:\/\/tiefbau-oldenburg.de\/index.php\/wp-json\/wp\/v2\/media?parent=290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}